{"id":8865,"date":"2025-01-06T10:52:09","date_gmt":"2025-01-06T15:52:09","guid":{"rendered":"https:\/\/portagepower.com\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/"},"modified":"2025-10-08T10:47:12","modified_gmt":"2025-10-08T15:47:12","slug":"dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere","status":"publish","type":"post","link":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/","title":{"rendered":"Dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant les chutes de la chaudi\u00e8re"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_empty_space height=\u00a0\u00bb20px\u00a0\u00bb]\n<blockquote class=\"qodef-blockquote-shortcode\"  >\n\t<h4 class=\"qodef-blockquote-text\">\n\t<span>\u00c0 la fin d\u2019une longue journ\u00e9e, vous vous asseyez dans votre fauteuil. Vous allumez quelques lumi\u00e8res et peut-\u00eatre la t\u00e9l\u00e9vision. Vous faites ces gestes parce que vous vous attendez \u00e0 ce que tout fonctionne comme il se doit \u2013 autrement dit, que vos lampes et que vos appareils soient sous tension. Il suffit de s\u2019arr\u00eater \u00e0 cette sc\u00e8ne habituelle pour reconna\u00eetre \u00e0 quel point il est formidable d\u2019avoir si facilement acc\u00e8s aux sources d\u2019alimentation en \u00e9lectricit\u00e9 \u00e0 la maison, au travail et \u00e0 d\u2019innombrables autres endroits partout dans la ville. D\u2019o\u00f9 vient cette \u00e9lectricit\u00e9? Comment la produit-on? \u00c0 Ottawa, les chutes de la Chaudi\u00e8re constituent un lieu d\u2019int\u00e9r\u00eat remarquable o\u00f9 se trouvent plusieurs centrales hydro\u00e9lectriques qui contribuent \u00e0 l\u2019alimentation en \u00e9lectricit\u00e9 de la province.<\/span>\n\t<\/h4>\n<\/blockquote>[vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_column_text]Voici dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant ces chutes :<br \/>\n&nbsp;<\/p>\n<ol>\n<li><strong>L\u2019histoire \u00e0 l\u2019origine du nom<br \/>\n<\/strong>En raison de la forme des chutes qui, \u00e0 l\u2019\u00e9poque, ressemblaient \u00e0 un chaudron et de la bruine s\u2019\u00e9levant des eaux agit\u00e9es, la Premi\u00e8re Nation algonquine appelait les chutes \u00ab Akikok \u00bb (mot qui signifie \u00ab bouilloire \u00bb ou \u00ab chaudron \u00bb). C\u2019est pourquoi l\u2019explorateur fran\u00e7ais Samuel de Champlain leur a donn\u00e9 le nom de \u00ab Chaudi\u00e8re \u00bb.<\/li>\n<li><strong>La taille des chutes<\/strong><br \/>\nLa splendeur des chutes est attribuable en partie \u00e0 leur immense taille. Elles ont une largeur d\u2019environ 60 m (200 pi) et une d\u00e9nivellation de 15 m (49 pi).<\/li>\n<li><strong>Des racines sacr\u00e9es<\/strong><br \/>\nLe site des chutes de la Chaudi\u00e8re est consid\u00e9r\u00e9 comme un lieu sacr\u00e9 pour les Algonquins Anishinaabe et d\u2019autres Premi\u00e8res Nations.<\/li>\n<li><strong>Un catalyseur de l\u2019essor industriel<\/strong><br \/>\nLes chutes de la Chaudi\u00e8re fournissaient l\u2019\u00e9nergie hydraulique aux nombreuses scieries et usines qui occupaient les berges de la rivi\u00e8re des Outaouais pendant l\u2019essor industriel du milieu du xixesi\u00e8cle.<\/li>\n<li><strong>Site de la plus ancienne centrale hydro\u00e9lectrique<\/strong><br \/>\nLa centrale no2, dans l\u2019\u00eele Victoria situ\u00e9e tout pr\u00e8s, est la plus ancienne centrale hydro\u00e9lectrique encore en exploitation au Canada. Depuis la brasserie Mill Street, sur la rue Wellington, on peut tr\u00e8s bien observer cette centrale en pleine action.<\/li>\n<li><strong>Production d\u2019\u00e9nergie propre<\/strong><br \/>\nOn trouve aux chutes de la Chaudi\u00e8re six centrales au fil de l\u2019eau qui tirent parti du d\u00e9bit naturel de la rivi\u00e8re pour produire de l\u2019\u00e9nergie propre sans \u00e9mettre de dioxyde de carbone ni de m\u00e9thane.<\/li>\n<li><strong>Alimentation en \u00e9lectricit\u00e9 de milliers d\u2019habitations<\/strong><br \/>\nL\u2019\u00e9lectricit\u00e9 produite aux chutes de la Chaudi\u00e8re permet d\u2019alimenter 20 000 habitations, tout en r\u00e9duisant les \u00e9missions de dioxyde de carbone de 115 000 tonnes par an comparativement aux barrages hydro\u00e9lectriques classiques.<\/li>\n<li><strong>Surveillance continue<\/strong><br \/>\nDepuis la mise en service du barrage-vo\u00fbte aux chutes de la Chaudi\u00e8re au d\u00e9but des ann\u00e9es 1900, des employ\u00e9s en assurent l\u2019exploitation en tout temps.<\/li>\n<li><strong>Supports Species Revival<\/strong><br \/>\nLa centrale est munie d\u2019un syst\u00e8me de d\u00e9rivation et d\u2019une passe \u00e0 anguilles pour aider l\u2019anguille d\u2019Am\u00e9rique, esp\u00e8ce en voie de disparition, \u00e0 migrer en toute s\u00e9curit\u00e9 en amont et en aval de la rivi\u00e8re des Outaouais. Pour en savoir plus, consultez notre <a href=\"https:\/\/portagepower.com\/fr\/le-retablissement-dune-espece-a-la-rescousse-de-languille-damerique\/\">blogue<\/a>!<\/li>\n<li><strong>Il y a une application pour cela!<br \/>\n<\/strong>Nous sommes fiers d\u2019affirmer qu\u2019il existe une application mobile gratuite pour les chutes de la Chaudi\u00e8re. Utilisez-la pour voir des photos d\u2019\u00e9poque, des vid\u00e9os et bien d\u2019autre contenu! Vous pouvez t\u00e9l\u00e9charger la version pour appareils Android en cliquant <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.hydroottawa.chaudierefalls\">ici<\/a> et celle pour appareils Apple en cliquant <a href=\"https:\/\/itunes.apple.com\/ca\/app\/visit-chaudi%C3%A8re-falls\/id1326192999?mt=8\">ici<\/a>!<\/li>\n<\/ol>\n<p>[\/vc_column_text][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb8755&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_column_text]Pour couronner le tout, nous vous offrons la possibilit\u00e9 de visiter notre centrale ultramoderne aux chutes de la Chaudi\u00e8re pour constater par vous-m\u00eame toutes ces caract\u00e9ristiques! Pour en savoir plus, consultez le <a href=\"http:\/\/chaudierefalls.com\/?utm_source=portage-power&amp;utm_medium=blog-article&amp;utm_campaign=green-doors-open\">site Web des chutes de la Chaudi\u00e8re.<\/a>.<\/p>\n<p>Nous esp\u00e9rons que ces faits amusants aideront \u00e0 susciter votre enthousiasme et vous permettront d\u2019impressionner vos parents et amis lorsque vous planifierez votre visite.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00c0 Ottawa, les chutes de la Chaudi\u00e8re constituent un lieu d\u2019int\u00e9r\u00eat remarquable o\u00f9 se trouvent plusieurs centrales hydro\u00e9lectriques qui contribuent \u00e0 l\u2019alimentation en \u00e9lectricit\u00e9 de la province.<\/p>\n","protected":false},"author":7,"featured_media":10368,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[165,197,199],"tags":[167,173,172,166],"class_list":["post-8865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogue","category-hydroelectricite","category-region-de-la-capitale-nationale","tag-chaudiere-falls-fr","tag-history-fr","tag-hydroelectric-fr","tag-sustainability-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant les chutes de la chaudi\u00e8re<\/title>\n<meta name=\"description\" content=\"\u00c0 Ottawa, les chutes de la Chaudi\u00e8re constituent un lieu d\u2019int\u00e9r\u00eat remarquable o\u00f9 se trouvent plusieurs centrales hydro\u00e9lectriques qui contribuent \u00e0 l\u2019alimentation en \u00e9lectricit\u00e9 de la province.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant les chutes de la chaudi\u00e8re\" \/>\n<meta property=\"og:description\" content=\"\u00c0 Ottawa, les chutes de la Chaudi\u00e8re constituent un lieu d\u2019int\u00e9r\u00eat remarquable o\u00f9 se trouvent plusieurs centrales hydro\u00e9lectriques qui contribuent \u00e0 l\u2019alimentation en \u00e9lectricit\u00e9 de la province.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/\" \/>\n<meta property=\"og:site_name\" content=\"Portage Power\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-06T15:52:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T15:47:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portagepower.com\/wp-content\/uploads\/2019\/02\/LUT9959-compress.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portage Power\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portage Power\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/\"},\"author\":{\"name\":\"Portage Power\",\"@id\":\"https:\\\/\\\/portagepower.com\\\/#\\\/schema\\\/person\\\/5bc3f6d8f6e3a55608911ed73915d536\"},\"headline\":\"Dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant les chutes de la chaudi\u00e8re\",\"datePublished\":\"2025-01-06T15:52:09+00:00\",\"dateModified\":\"2025-10-08T15:47:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/\"},\"wordCount\":744,\"image\":{\"@id\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portagepower.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/LUT9959-compress.jpg\",\"keywords\":[\"Chaudi\u00e8re Falls\",\"history\",\"hydroelectric\",\"sustainability\"],\"articleSection\":[\"Blogue\",\"Hydro\u00e9lectricit\u00e9\",\"R\u00e9gion de la capitale nationale\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/\",\"url\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/\",\"name\":\"Dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant les chutes de la chaudi\u00e8re\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portagepower.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portagepower.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/LUT9959-compress.jpg\",\"datePublished\":\"2025-01-06T15:52:09+00:00\",\"dateModified\":\"2025-10-08T15:47:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/portagepower.com\\\/#\\\/schema\\\/person\\\/5bc3f6d8f6e3a55608911ed73915d536\"},\"description\":\"\u00c0 Ottawa, les chutes de la Chaudi\u00e8re constituent un lieu d\u2019int\u00e9r\u00eat remarquable o\u00f9 se trouvent plusieurs centrales hydro\u00e9lectriques qui contribuent \u00e0 l\u2019alimentation en \u00e9lectricit\u00e9 de la province.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/portagepower.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/LUT9959-compress.jpg\",\"contentUrl\":\"https:\\\/\\\/portagepower.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/LUT9959-compress.jpg\",\"width\":1920,\"height\":1278},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant les chutes de la chaudi\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/portagepower.com\\\/#website\",\"url\":\"https:\\\/\\\/portagepower.com\\\/\",\"name\":\"Portage Power\",\"description\":\"Generating Renewable Power\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/portagepower.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/portagepower.com\\\/#\\\/schema\\\/person\\\/5bc3f6d8f6e3a55608911ed73915d536\",\"name\":\"Portage Power\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/425391459e7e1bb02963aaa54098f1e042094a767f3d60a4d2d191e13da5ab78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/425391459e7e1bb02963aaa54098f1e042094a767f3d60a4d2d191e13da5ab78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/425391459e7e1bb02963aaa54098f1e042094a767f3d60a4d2d191e13da5ab78?s=96&d=mm&r=g\",\"caption\":\"Portage Power\"},\"url\":\"https:\\\/\\\/portagepower.com\\\/fr\\\/author\\\/theboss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant les chutes de la chaudi\u00e8re","description":"\u00c0 Ottawa, les chutes de la Chaudi\u00e8re constituent un lieu d\u2019int\u00e9r\u00eat remarquable o\u00f9 se trouvent plusieurs centrales hydro\u00e9lectriques qui contribuent \u00e0 l\u2019alimentation en \u00e9lectricit\u00e9 de la province.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/","og_locale":"fr_FR","og_type":"article","og_title":"Dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant les chutes de la chaudi\u00e8re","og_description":"\u00c0 Ottawa, les chutes de la Chaudi\u00e8re constituent un lieu d\u2019int\u00e9r\u00eat remarquable o\u00f9 se trouvent plusieurs centrales hydro\u00e9lectriques qui contribuent \u00e0 l\u2019alimentation en \u00e9lectricit\u00e9 de la province.","og_url":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/","og_site_name":"Portage Power","article_published_time":"2025-01-06T15:52:09+00:00","article_modified_time":"2025-10-08T15:47:12+00:00","og_image":[{"width":1920,"height":1278,"url":"https:\/\/portagepower.com\/wp-content\/uploads\/2019\/02\/LUT9959-compress.jpg","type":"image\/jpeg"}],"author":"Portage Power","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Portage Power","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/#article","isPartOf":{"@id":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/"},"author":{"name":"Portage Power","@id":"https:\/\/portagepower.com\/#\/schema\/person\/5bc3f6d8f6e3a55608911ed73915d536"},"headline":"Dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant les chutes de la chaudi\u00e8re","datePublished":"2025-01-06T15:52:09+00:00","dateModified":"2025-10-08T15:47:12+00:00","mainEntityOfPage":{"@id":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/"},"wordCount":744,"image":{"@id":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/#primaryimage"},"thumbnailUrl":"https:\/\/portagepower.com\/wp-content\/uploads\/2019\/02\/LUT9959-compress.jpg","keywords":["Chaudi\u00e8re Falls","history","hydroelectric","sustainability"],"articleSection":["Blogue","Hydro\u00e9lectricit\u00e9","R\u00e9gion de la capitale nationale"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/","url":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/","name":"Dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant les chutes de la chaudi\u00e8re","isPartOf":{"@id":"https:\/\/portagepower.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/#primaryimage"},"image":{"@id":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/#primaryimage"},"thumbnailUrl":"https:\/\/portagepower.com\/wp-content\/uploads\/2019\/02\/LUT9959-compress.jpg","datePublished":"2025-01-06T15:52:09+00:00","dateModified":"2025-10-08T15:47:12+00:00","author":{"@id":"https:\/\/portagepower.com\/#\/schema\/person\/5bc3f6d8f6e3a55608911ed73915d536"},"description":"\u00c0 Ottawa, les chutes de la Chaudi\u00e8re constituent un lieu d\u2019int\u00e9r\u00eat remarquable o\u00f9 se trouvent plusieurs centrales hydro\u00e9lectriques qui contribuent \u00e0 l\u2019alimentation en \u00e9lectricit\u00e9 de la province.","breadcrumb":{"@id":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/#primaryimage","url":"https:\/\/portagepower.com\/wp-content\/uploads\/2019\/02\/LUT9959-compress.jpg","contentUrl":"https:\/\/portagepower.com\/wp-content\/uploads\/2019\/02\/LUT9959-compress.jpg","width":1920,"height":1278},{"@type":"BreadcrumbList","@id":"https:\/\/portagepower.com\/fr\/dix-faits-captivants-que-vous-ne-connaissez-peut-etre-pas-concernant-les-chutes-de-la-chaudiere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/portagepower.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Dix faits captivants que vous ne connaissez peut-\u00eatre pas concernant les chutes de la chaudi\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/portagepower.com\/#website","url":"https:\/\/portagepower.com\/","name":"Portage Power","description":"Generating Renewable Power","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portagepower.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/portagepower.com\/#\/schema\/person\/5bc3f6d8f6e3a55608911ed73915d536","name":"Portage Power","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/425391459e7e1bb02963aaa54098f1e042094a767f3d60a4d2d191e13da5ab78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/425391459e7e1bb02963aaa54098f1e042094a767f3d60a4d2d191e13da5ab78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/425391459e7e1bb02963aaa54098f1e042094a767f3d60a4d2d191e13da5ab78?s=96&d=mm&r=g","caption":"Portage Power"},"url":"https:\/\/portagepower.com\/fr\/author\/theboss\/"}]}},"_links":{"self":[{"href":"https:\/\/portagepower.com\/fr\/wp-json\/wp\/v2\/posts\/8865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portagepower.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portagepower.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portagepower.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/portagepower.com\/fr\/wp-json\/wp\/v2\/comments?post=8865"}],"version-history":[{"count":5,"href":"https:\/\/portagepower.com\/fr\/wp-json\/wp\/v2\/posts\/8865\/revisions"}],"predecessor-version":[{"id":8871,"href":"https:\/\/portagepower.com\/fr\/wp-json\/wp\/v2\/posts\/8865\/revisions\/8871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portagepower.com\/fr\/wp-json\/wp\/v2\/media\/10368"}],"wp:attachment":[{"href":"https:\/\/portagepower.com\/fr\/wp-json\/wp\/v2\/media?parent=8865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portagepower.com\/fr\/wp-json\/wp\/v2\/categories?post=8865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portagepower.com\/fr\/wp-json\/wp\/v2\/tags?post=8865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}